{"id":783,"date":"2026-02-13T19:05:28","date_gmt":"2026-02-13T09:05:28","guid":{"rendered":"https:\/\/solicitudesta.es\/noticias\/?p=783"},"modified":"2026-02-12T14:38:57","modified_gmt":"2026-02-12T04:38:57","slug":"los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion","status":"publish","type":"post","link":"https:\/\/solicitudesta.es\/noticias\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\/","title":{"rendered":"Los \u00c1ngeles, duramente golpeada por las redadas indiscriminadas contra la inmigraci\u00f3n."},"content":{"rendered":"<p>Las redadas indiscriminadas y a gran escala llevadas a cabo por la administraci\u00f3n de Donald Trump en el sur de California durante su segundo mandato han afectado significativamente la econom\u00eda local. Dado que los negocios en las zonas c\u00e9ntricas, incluyendo Koreatown y el centro de la ciudad, han sufrido p\u00e9rdidas significativas, el gobierno de la ciudad de Los \u00c1ngeles ha tomado medidas adicionales para proteger a los residentes de estas redadas.<br \/>\nSeg\u00fan un informe publicado recientemente por el condado de Los \u00c1ngeles, las redadas federales de inmigraci\u00f3n y las protestas y disturbios resultantes en Los \u00c1ngeles desde el verano pasado han costado a la econom\u00eda local aproximadamente mil millones de d\u00f3lares en p\u00e9rdidas de producci\u00f3n, ventas y salarios. Los peque\u00f1os negocios, en particular los restaurantes, en zonas con alta densidad de poblaci\u00f3n inmigrante, incluyendo Westlake, cerca de Koreatown, se han visto particularmente afectados. El informe, encargado por la Junta de Supervisores del Condado de Los \u00c1ngeles y coescrito por la Oficina de Oportunidades Econ\u00f3micas del Condado y la Corporaci\u00f3n de Desarrollo Econ\u00f3mico del Condado de Los \u00c1ngeles (LAEDC), revel\u00f3 que las \u00e1reas con una alta concentraci\u00f3n de redadas de ICE experimentaron un aumento en el cierre de negocios, una fuerte disminuci\u00f3n en el tr\u00e1fico de clientes y una disminuci\u00f3n de aproximadamente 17,000 usuarios del transporte p\u00fablico.<\/p>\n<p>En una encuesta a peque\u00f1os negocios, la mayor\u00eda de los encuestados afirm\u00f3: \u00abLos clientes se muestran reacios a salir a comer fuera por temor a las medidas represivas\u00bb. De hecho, se estima que aproximadamente 950,000 inmigrantes indocumentados residen en el Condado de Los \u00c1ngeles, lo que genera un impacto econ\u00f3mico de $240 mil millones anuales y representa aproximadamente el 17% de la actividad econ\u00f3mica total del condado.<\/p>\n<p>Los an\u00e1lisis tambi\u00e9n muestran que el 37% de los trabajadores de limpieza y mantenimiento, el 25% de los trabajadores de preparaci\u00f3n y servicio de alimentos y el 40% de los trabajadores de la construcci\u00f3n son indocumentados. Si estos inmigrantes se marchan o se esconden, es inevitable que se produzca una escasez de mano de obra y una disminuci\u00f3n del consumo. El informe identific\u00f3 espec\u00edficamente el c\u00f3digo postal 91402, que abarca Mission Hills, Panorama City y North Hills, como la zona m\u00e1s atacada por las redadas. Las zonas de clase trabajadora y con gran afluencia de inmigrantes, como Westlake, Bell, Peco Rivera y el Este de Los \u00c1ngeles, tambi\u00e9n se clasificaron como econ\u00f3micamente vulnerables.<\/p>\n<p>Los negocios en estas zonas tienen un promedio de empleados m\u00e1s reducido y salarios m\u00e1s bajos, lo que los hace m\u00e1s vulnerables a las crisis externas. Mientras tanto, la alcaldesa de Los \u00c1ngeles, Karen Bass, anunci\u00f3 una orden ejecutiva el d\u00eda 10 para fortalecer la protecci\u00f3n de los inmigrantes.<\/p>\n<p>La nueva directiva exige que todos los departamentos de la ciudad desarrollen un plan de respuesta para la aplicaci\u00f3n de las leyes federales de inmigraci\u00f3n en un plazo de dos semanas y reafirma las ordenanzas de \u00abciudad santuario\u00bb para garantizar que los recursos y el personal de la ciudad no se utilicen para iniciativas federales de deportaci\u00f3n.<\/p>\n<p>Tambi\u00e9n limita la aplicaci\u00f3n de las leyes federales de inmigraci\u00f3n en las propiedades de la ciudad y designa un oficial de enlace dedicado a abordar cualquier posible incidente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las redadas indiscriminadas y a gran escala llevadas a cabo por la administraci\u00f3n de Donald Trump en el sur de California durante su segundo mandato han afectado significativamente la econom\u00eda local. Dado que los negocios en las zonas c\u00e9ntricas, incluyendo Koreatown y el centro de la ciudad, han sufrido p\u00e9rdidas significativas, el gobierno de la &hellip; <a href=\"https:\/\/solicitudesta.es\/noticias\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">Los \u00c1ngeles, duramente golpeada por las redadas indiscriminadas contra la inmigraci\u00f3n.<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":784,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-783","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esta-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los \u00c1ngeles, duramente golpeada por las redadas indiscriminadas contra la inmigraci\u00f3n. - Noticias EE.UU - ESTA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solicitudesta.es\/noticias\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los \u00c1ngeles, duramente golpeada por las redadas indiscriminadas contra la inmigraci\u00f3n. - Noticias EE.UU - ESTA\" \/>\n<meta property=\"og:description\" content=\"Las redadas indiscriminadas y a gran escala llevadas a cabo por la administraci\u00f3n de Donald Trump en el sur de California durante su segundo mandato han afectado significativamente la econom\u00eda local. Dado que los negocios en las zonas c\u00e9ntricas, incluyendo Koreatown y el centro de la ciudad, han sufrido p\u00e9rdidas significativas, el gobierno de la &hellip; Sigue leyendo Los \u00c1ngeles, duramente golpeada por las redadas indiscriminadas contra la inmigraci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solicitudesta.es\/noticias\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias EE.UU - ESTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/US-Visa-Travel-Pass-1053927617993589\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-13T09:05:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solicitudesta.es\/noticias\/wp-content\/uploads\/2026\/02\/ESTA-SPAIN-13.02.2026.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@visatravelpass\" \/>\n<meta name=\"twitter:site\" content=\"@visatravelpass\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/#\\\/schema\\\/person\\\/bf84534931a3fef6904dbc3d5727662e\"},\"headline\":\"Los \u00c1ngeles, duramente golpeada por las redadas indiscriminadas contra la inmigraci\u00f3n.\",\"datePublished\":\"2026-02-13T09:05:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\\\/\"},\"wordCount\":578,\"publisher\":{\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/ESTA-SPAIN-13.02.2026.jpg\",\"articleSection\":[\"ESTA Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\\\/\",\"url\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\\\/\",\"name\":\"Los \u00c1ngeles, duramente golpeada por las redadas indiscriminadas contra la inmigraci\u00f3n. - Noticias EE.UU - ESTA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/ESTA-SPAIN-13.02.2026.jpg\",\"datePublished\":\"2026-02-13T09:05:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/ESTA-SPAIN-13.02.2026.jpg\",\"contentUrl\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/ESTA-SPAIN-13.02.2026.jpg\",\"width\":700,\"height\":467},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los \u00c1ngeles, duramente golpeada por las redadas indiscriminadas contra la inmigraci\u00f3n.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/\",\"name\":\"Noticias EE.UU - ESTA\",\"description\":\"Noticias y Actualidades sobre EE.UU, Viajes y Solicitud ESTA EE.UU\",\"publisher\":{\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/#organization\",\"name\":\"U.S. ESTA Travel Pass\",\"url\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/usvisatravelpass.com\\\/news\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/logo1.png\",\"contentUrl\":\"https:\\\/\\\/usvisatravelpass.com\\\/news\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/logo1.png\",\"width\":297,\"height\":90,\"caption\":\"U.S. ESTA Travel Pass\"},\"image\":{\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/US-Visa-Travel-Pass-1053927617993589\\\/\",\"https:\\\/\\\/x.com\\\/visatravelpass\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/#\\\/schema\\\/person\\\/bf84534931a3fef6904dbc3d5727662e\",\"name\":\"Admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los \u00c1ngeles, duramente golpeada por las redadas indiscriminadas contra la inmigraci\u00f3n. - Noticias EE.UU - ESTA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solicitudesta.es\/noticias\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\/","og_locale":"es_ES","og_type":"article","og_title":"Los \u00c1ngeles, duramente golpeada por las redadas indiscriminadas contra la inmigraci\u00f3n. - Noticias EE.UU - ESTA","og_description":"Las redadas indiscriminadas y a gran escala llevadas a cabo por la administraci\u00f3n de Donald Trump en el sur de California durante su segundo mandato han afectado significativamente la econom\u00eda local. Dado que los negocios en las zonas c\u00e9ntricas, incluyendo Koreatown y el centro de la ciudad, han sufrido p\u00e9rdidas significativas, el gobierno de la &hellip; Sigue leyendo Los \u00c1ngeles, duramente golpeada por las redadas indiscriminadas contra la inmigraci\u00f3n.","og_url":"https:\/\/solicitudesta.es\/noticias\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\/","og_site_name":"Noticias EE.UU - ESTA","article_publisher":"https:\/\/www.facebook.com\/US-Visa-Travel-Pass-1053927617993589\/","article_published_time":"2026-02-13T09:05:28+00:00","og_image":[{"width":700,"height":467,"url":"https:\/\/solicitudesta.es\/noticias\/wp-content\/uploads\/2026\/02\/ESTA-SPAIN-13.02.2026.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_creator":"@visatravelpass","twitter_site":"@visatravelpass","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/solicitudesta.es\/noticias\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\/#article","isPartOf":{"@id":"https:\/\/solicitudesta.es\/noticias\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\/"},"author":{"name":"Admin","@id":"https:\/\/solicitudesta.es\/noticias\/#\/schema\/person\/bf84534931a3fef6904dbc3d5727662e"},"headline":"Los \u00c1ngeles, duramente golpeada por las redadas indiscriminadas contra la inmigraci\u00f3n.","datePublished":"2026-02-13T09:05:28+00:00","mainEntityOfPage":{"@id":"https:\/\/solicitudesta.es\/noticias\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\/"},"wordCount":578,"publisher":{"@id":"https:\/\/solicitudesta.es\/noticias\/#organization"},"image":{"@id":"https:\/\/solicitudesta.es\/noticias\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\/#primaryimage"},"thumbnailUrl":"https:\/\/solicitudesta.es\/noticias\/wp-content\/uploads\/2026\/02\/ESTA-SPAIN-13.02.2026.jpg","articleSection":["ESTA Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/solicitudesta.es\/noticias\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\/","url":"https:\/\/solicitudesta.es\/noticias\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\/","name":"Los \u00c1ngeles, duramente golpeada por las redadas indiscriminadas contra la inmigraci\u00f3n. - Noticias EE.UU - ESTA","isPartOf":{"@id":"https:\/\/solicitudesta.es\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solicitudesta.es\/noticias\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\/#primaryimage"},"image":{"@id":"https:\/\/solicitudesta.es\/noticias\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\/#primaryimage"},"thumbnailUrl":"https:\/\/solicitudesta.es\/noticias\/wp-content\/uploads\/2026\/02\/ESTA-SPAIN-13.02.2026.jpg","datePublished":"2026-02-13T09:05:28+00:00","breadcrumb":{"@id":"https:\/\/solicitudesta.es\/noticias\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solicitudesta.es\/noticias\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/solicitudesta.es\/noticias\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\/#primaryimage","url":"https:\/\/solicitudesta.es\/noticias\/wp-content\/uploads\/2026\/02\/ESTA-SPAIN-13.02.2026.jpg","contentUrl":"https:\/\/solicitudesta.es\/noticias\/wp-content\/uploads\/2026\/02\/ESTA-SPAIN-13.02.2026.jpg","width":700,"height":467},{"@type":"BreadcrumbList","@id":"https:\/\/solicitudesta.es\/noticias\/los-angeles-duramente-golpeada-por-las-redadas-indiscriminadas-contra-la-inmigracion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solicitudesta.es\/noticias\/"},{"@type":"ListItem","position":2,"name":"Los \u00c1ngeles, duramente golpeada por las redadas indiscriminadas contra la inmigraci\u00f3n."}]},{"@type":"WebSite","@id":"https:\/\/solicitudesta.es\/noticias\/#website","url":"https:\/\/solicitudesta.es\/noticias\/","name":"Noticias EE.UU - ESTA","description":"Noticias y Actualidades sobre EE.UU, Viajes y Solicitud ESTA EE.UU","publisher":{"@id":"https:\/\/solicitudesta.es\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solicitudesta.es\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/solicitudesta.es\/noticias\/#organization","name":"U.S. ESTA Travel Pass","url":"https:\/\/solicitudesta.es\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/solicitudesta.es\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/usvisatravelpass.com\/news\/wp-content\/uploads\/2016\/08\/logo1.png","contentUrl":"https:\/\/usvisatravelpass.com\/news\/wp-content\/uploads\/2016\/08\/logo1.png","width":297,"height":90,"caption":"U.S. ESTA Travel Pass"},"image":{"@id":"https:\/\/solicitudesta.es\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/US-Visa-Travel-Pass-1053927617993589\/","https:\/\/x.com\/visatravelpass"]},{"@type":"Person","@id":"https:\/\/solicitudesta.es\/noticias\/#\/schema\/person\/bf84534931a3fef6904dbc3d5727662e","name":"Admin"}]}},"_links":{"self":[{"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/posts\/783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/comments?post=783"}],"version-history":[{"count":1,"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/posts\/783\/revisions"}],"predecessor-version":[{"id":785,"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/posts\/783\/revisions\/785"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/media\/784"}],"wp:attachment":[{"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/media?parent=783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/categories?post=783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/tags?post=783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}