{"id":477,"date":"2024-05-03T19:00:55","date_gmt":"2024-05-03T09:00:55","guid":{"rendered":"https:\/\/solicitudesta.es\/noticias\/?p=477"},"modified":"2024-04-30T10:02:35","modified_gmt":"2024-04-30T00:02:35","slug":"el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles","status":"publish","type":"post","link":"https:\/\/solicitudesta.es\/noticias\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\/","title":{"rendered":"El problem\u00e1tico problema de las personas sin hogar en Los \u00c1ngeles."},"content":{"rendered":"<p>En Los \u00c1ngeles (LA), la ciudad m\u00e1s grande del oeste, el problema de las personas sin hogar es un problema importante. Los turistas que llegaron a Los \u00c1ngeles esperando ver el fant\u00e1stico paisaje urbano de la pel\u00edcula &#8216;La La Land&#8217; se encontraron con una ciudad de tiendas de campa\u00f1a para personas sin hogar que se hab\u00eda apoderado de cada rinc\u00f3n de la ciudad y experimentaron un &#8216;tiempo de realizaci\u00f3n&#8217;. La mayor\u00eda de las ciudades m\u00e1s grandes del mundo muestran disparidades extremas entre ricos y pobres, pero el centro de Los \u00c1ngeles (LADT), que est\u00e1 lleno de tiendas de campa\u00f1a para personas sin hogar, y las mansiones ultralujosas de Beverly Hills, ubicadas a solo 30 minutos en auto a partir de ah\u00ed, presentar un paisaje verdaderamente opuesto.<\/p>\n<p>Seg\u00fan un recuento publicado por el Departamento de Vivienda y Desarrollo Urbano (HUD) en diciembre de 2022, el n\u00famero de personas sin hogar en California es 171,521, lo que representa aproximadamente el 30% del n\u00famero total de personas sin hogar en los Estados Unidos (582,462 personas).\u00a0 Seg\u00fan la Agencia de Servicios para Personas sin Hogar de Los \u00c1ngeles (LAHSA), en enero del a\u00f1o pasado, el n\u00famero de personas sin hogar en el condado de Los \u00c1ngeles era de 75,518 y el n\u00famero de personas sin hogar en Los \u00c1ngeles era de 46,260. Seg\u00fan estas estad\u00edsticas, aproximadamente un tercio de todas las personas sin hogar en los Estados Unidos viven en California.<\/p>\n<p>Hay muchos factores que contribuyen al elevado n\u00famero de personas sin hogar en Los \u00c1ngeles, pero lo primero que hay que mencionar es el clima templado que permite que haya personas sin hogar durante todo el a\u00f1o. Incluso en pleno invierno, la temperatura no desciende por debajo del punto de congelaci\u00f3n y, aunque el sol calienta en pleno verano, la humedad es baja y hace fresco cuando te pones a la sombra.<\/p>\n<p>Gracias a esto, casi no hay riesgo de morir congelado o de sufrir un golpe de calor incluso si est\u00e1s en la calle en Los \u00c1ngeles. Adem\u00e1s, el terreno es grande y hay muchos parques aqu\u00ed y all\u00e1, por lo que hay mucho espacio para montar una tienda de campa\u00f1a. Adem\u00e1s, incluso en Estados Unidos, los alquileres de viviendas particularmente caros se consideran un factor estructural que lleva a personas de ingresos marginalmente bajos a quedarse sin hogar. Dado que el problema de las personas sin hogar es tan grave, las autoridades de la ciudad tambi\u00e9n est\u00e1n preocupadas por encontrar una soluci\u00f3n al problema.<\/p>\n<p>El alcalde Bath asign\u00f3 un presupuesto total de 1,300 millones de d\u00f3lares a las personas sin hogar e invirti\u00f3 una parte de ello en el programa &#8216;Inside Safe&#8217;. Seg\u00fan las autoridades de la ciudad, hasta el d\u00eda 12, alrededor de 2,600 personas sin hogar se hab\u00edan mudado a viviendas bajo techo a trav\u00e9s de este programa, y aproximadamente la mitad de ellos viv\u00edan en instalaciones de alojamiento como hoteles o moteles. Sin embargo, 613 personas, m\u00e1s de una cuarta parte de todas las personas sin hogar que participaron en este programa, regresaron a las calles.<\/p>\n<p>A medida que crec\u00edan las presiones financieras de la ciudad debido al alto costo de alojar a las personas sin hogar en alojamientos temporales y al aumento de los costos en otras \u00e1reas como la seguridad p\u00fablica, las autoridades lanzaron la campa\u00f1a &#8216;LA4LA&#8217; para recaudar fondos insuficientes a trav\u00e9s de donaciones del sector privado.<\/p>\n<p>El alcalde Bath anunci\u00f3 esta campa\u00f1a en su discurso sobre el estado de la ciudad el d\u00eda 15 y enfatiz\u00f3: \u00abAhora debemos aprovechar la humanidad y la generosidad del sector privado\u00bb. Al mismo tiempo, enfatiz\u00f3, \u00abestamos pidiendo a los angelinos m\u00e1s ricos que participen en este esfuerzo donando fondos\u00bb. Hizo un llamamiento a los ricos para que contribuyan con grandes sumas de dinero para ayudar a establecer una base de viviendas para las personas sin hogar. Esta campa\u00f1a del alcalde Bath, un dem\u00f3crata, fue aplaudida por progresistas y fil\u00e1ntropos.<\/p>\n<p>El inversionista y fil\u00e1ntropo con sede en Beverly Hills Steven J. Lubeck asisti\u00f3 al discurso sobre el estado de la ciudad del alcalde Bath y elogi\u00f3 su campa\u00f1a LA4LA, revelando que le hab\u00eda donado $1 mill\u00f3n. Sin embargo, tambi\u00e9n hay comentarios amargos por parte de algunos sectores.<\/p>\n<p>El California Globe, un medio de comunicaci\u00f3n local, inform\u00f3: \u00abMuchas personas criticaron el \u00faltimo intento del alcalde Bath como &#8216;en el mejor de los casos, un intento de inducir a los residentes ricos a pagar m\u00e1s impuestos a la ciudad'\u00bb. pero no creo que vayan a donar a LA4LA\u201d, dijo Early Kelly, un abogado que ha estado involucrado en la gesti\u00f3n de varias organizaciones ben\u00e9ficas y. \u201c(LA4LA) es un mal plan\u201d, dijo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Los \u00c1ngeles (LA), la ciudad m\u00e1s grande del oeste, el problema de las personas sin hogar es un problema importante. Los turistas que llegaron a Los \u00c1ngeles esperando ver el fant\u00e1stico paisaje urbano de la pel\u00edcula &#8216;La La Land&#8217; se encontraron con una ciudad de tiendas de campa\u00f1a para personas sin hogar que se &hellip; <a href=\"https:\/\/solicitudesta.es\/noticias\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\/\" class=\"more-link\">Sigue leyendo <span class=\"screen-reader-text\">El problem\u00e1tico problema de las personas sin hogar en Los \u00c1ngeles.<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":478,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esta-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El problem\u00e1tico problema de las personas sin hogar en Los \u00c1ngeles. - Noticias EE.UU - ESTA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solicitudesta.es\/noticias\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El problem\u00e1tico problema de las personas sin hogar en Los \u00c1ngeles. - Noticias EE.UU - ESTA\" \/>\n<meta property=\"og:description\" content=\"En Los \u00c1ngeles (LA), la ciudad m\u00e1s grande del oeste, el problema de las personas sin hogar es un problema importante. Los turistas que llegaron a Los \u00c1ngeles esperando ver el fant\u00e1stico paisaje urbano de la pel\u00edcula &#8216;La La Land&#8217; se encontraron con una ciudad de tiendas de campa\u00f1a para personas sin hogar que se &hellip; Sigue leyendo El problem\u00e1tico problema de las personas sin hogar en Los \u00c1ngeles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solicitudesta.es\/noticias\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias EE.UU - ESTA\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/US-Visa-Travel-Pass-1053927617993589\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-03T09:00:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/solicitudesta.es\/noticias\/wp-content\/uploads\/2024\/04\/ESTA-SPAIN-26.04.2024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@visatravelpass\" \/>\n<meta name=\"twitter:site\" content=\"@visatravelpass\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/#\\\/schema\\\/person\\\/bf84534931a3fef6904dbc3d5727662e\"},\"headline\":\"El problem\u00e1tico problema de las personas sin hogar en Los \u00c1ngeles.\",\"datePublished\":\"2024-05-03T09:00:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\\\/\"},\"wordCount\":828,\"publisher\":{\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/ESTA-SPAIN-26.04.2024.jpg\",\"articleSection\":[\"ESTA Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\\\/\",\"url\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\\\/\",\"name\":\"El problem\u00e1tico problema de las personas sin hogar en Los \u00c1ngeles. - Noticias EE.UU - ESTA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/ESTA-SPAIN-26.04.2024.jpg\",\"datePublished\":\"2024-05-03T09:00:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/ESTA-SPAIN-26.04.2024.jpg\",\"contentUrl\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/ESTA-SPAIN-26.04.2024.jpg\",\"width\":700,\"height\":467},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El problem\u00e1tico problema de las personas sin hogar en Los \u00c1ngeles.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/\",\"name\":\"Noticias EE.UU - ESTA\",\"description\":\"Noticias y Actualidades sobre EE.UU, Viajes y Solicitud ESTA EE.UU\",\"publisher\":{\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/#organization\",\"name\":\"U.S. ESTA Travel Pass\",\"url\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/usvisatravelpass.com\\\/news\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/logo1.png\",\"contentUrl\":\"https:\\\/\\\/usvisatravelpass.com\\\/news\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/logo1.png\",\"width\":297,\"height\":90,\"caption\":\"U.S. ESTA Travel Pass\"},\"image\":{\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/US-Visa-Travel-Pass-1053927617993589\\\/\",\"https:\\\/\\\/x.com\\\/visatravelpass\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/solicitudesta.es\\\/noticias\\\/#\\\/schema\\\/person\\\/bf84534931a3fef6904dbc3d5727662e\",\"name\":\"Admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El problem\u00e1tico problema de las personas sin hogar en Los \u00c1ngeles. - Noticias EE.UU - ESTA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solicitudesta.es\/noticias\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\/","og_locale":"es_ES","og_type":"article","og_title":"El problem\u00e1tico problema de las personas sin hogar en Los \u00c1ngeles. - Noticias EE.UU - ESTA","og_description":"En Los \u00c1ngeles (LA), la ciudad m\u00e1s grande del oeste, el problema de las personas sin hogar es un problema importante. Los turistas que llegaron a Los \u00c1ngeles esperando ver el fant\u00e1stico paisaje urbano de la pel\u00edcula &#8216;La La Land&#8217; se encontraron con una ciudad de tiendas de campa\u00f1a para personas sin hogar que se &hellip; Sigue leyendo El problem\u00e1tico problema de las personas sin hogar en Los \u00c1ngeles.","og_url":"https:\/\/solicitudesta.es\/noticias\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\/","og_site_name":"Noticias EE.UU - ESTA","article_publisher":"https:\/\/www.facebook.com\/US-Visa-Travel-Pass-1053927617993589\/","article_published_time":"2024-05-03T09:00:55+00:00","og_image":[{"width":700,"height":467,"url":"https:\/\/solicitudesta.es\/noticias\/wp-content\/uploads\/2024\/04\/ESTA-SPAIN-26.04.2024.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_creator":"@visatravelpass","twitter_site":"@visatravelpass","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/solicitudesta.es\/noticias\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\/#article","isPartOf":{"@id":"https:\/\/solicitudesta.es\/noticias\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\/"},"author":{"name":"Admin","@id":"https:\/\/solicitudesta.es\/noticias\/#\/schema\/person\/bf84534931a3fef6904dbc3d5727662e"},"headline":"El problem\u00e1tico problema de las personas sin hogar en Los \u00c1ngeles.","datePublished":"2024-05-03T09:00:55+00:00","mainEntityOfPage":{"@id":"https:\/\/solicitudesta.es\/noticias\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\/"},"wordCount":828,"publisher":{"@id":"https:\/\/solicitudesta.es\/noticias\/#organization"},"image":{"@id":"https:\/\/solicitudesta.es\/noticias\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\/#primaryimage"},"thumbnailUrl":"https:\/\/solicitudesta.es\/noticias\/wp-content\/uploads\/2024\/04\/ESTA-SPAIN-26.04.2024.jpg","articleSection":["ESTA Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/solicitudesta.es\/noticias\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\/","url":"https:\/\/solicitudesta.es\/noticias\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\/","name":"El problem\u00e1tico problema de las personas sin hogar en Los \u00c1ngeles. - Noticias EE.UU - ESTA","isPartOf":{"@id":"https:\/\/solicitudesta.es\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/solicitudesta.es\/noticias\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\/#primaryimage"},"image":{"@id":"https:\/\/solicitudesta.es\/noticias\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\/#primaryimage"},"thumbnailUrl":"https:\/\/solicitudesta.es\/noticias\/wp-content\/uploads\/2024\/04\/ESTA-SPAIN-26.04.2024.jpg","datePublished":"2024-05-03T09:00:55+00:00","breadcrumb":{"@id":"https:\/\/solicitudesta.es\/noticias\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solicitudesta.es\/noticias\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/solicitudesta.es\/noticias\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\/#primaryimage","url":"https:\/\/solicitudesta.es\/noticias\/wp-content\/uploads\/2024\/04\/ESTA-SPAIN-26.04.2024.jpg","contentUrl":"https:\/\/solicitudesta.es\/noticias\/wp-content\/uploads\/2024\/04\/ESTA-SPAIN-26.04.2024.jpg","width":700,"height":467},{"@type":"BreadcrumbList","@id":"https:\/\/solicitudesta.es\/noticias\/el-problematico-problema-de-las-personas-sin-hogar-en-los-angeles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solicitudesta.es\/noticias\/"},{"@type":"ListItem","position":2,"name":"El problem\u00e1tico problema de las personas sin hogar en Los \u00c1ngeles."}]},{"@type":"WebSite","@id":"https:\/\/solicitudesta.es\/noticias\/#website","url":"https:\/\/solicitudesta.es\/noticias\/","name":"Noticias EE.UU - ESTA","description":"Noticias y Actualidades sobre EE.UU, Viajes y Solicitud ESTA EE.UU","publisher":{"@id":"https:\/\/solicitudesta.es\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solicitudesta.es\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/solicitudesta.es\/noticias\/#organization","name":"U.S. ESTA Travel Pass","url":"https:\/\/solicitudesta.es\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/solicitudesta.es\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/usvisatravelpass.com\/news\/wp-content\/uploads\/2016\/08\/logo1.png","contentUrl":"https:\/\/usvisatravelpass.com\/news\/wp-content\/uploads\/2016\/08\/logo1.png","width":297,"height":90,"caption":"U.S. ESTA Travel Pass"},"image":{"@id":"https:\/\/solicitudesta.es\/noticias\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/US-Visa-Travel-Pass-1053927617993589\/","https:\/\/x.com\/visatravelpass"]},{"@type":"Person","@id":"https:\/\/solicitudesta.es\/noticias\/#\/schema\/person\/bf84534931a3fef6904dbc3d5727662e","name":"Admin"}]}},"_links":{"self":[{"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/posts\/477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/comments?post=477"}],"version-history":[{"count":2,"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/posts\/477\/revisions"}],"predecessor-version":[{"id":480,"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/posts\/477\/revisions\/480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/media\/478"}],"wp:attachment":[{"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/media?parent=477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/categories?post=477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/solicitudesta.es\/noticias\/wp-json\/wp\/v2\/tags?post=477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}